{"id":20682,"date":"2026-03-27T16:20:13","date_gmt":"2026-03-27T20:20:13","guid":{"rendered":"https:\/\/vanderloubet.com.br\/deputado\/?p=20682"},"modified":"2026-03-27T17:47:01","modified_gmt":"2026-03-27T21:47:01","slug":"politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv","status":"publish","type":"post","link":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/","title":{"rendered":"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv"},"content":{"rendered":"<p>Campo Grande foi palco de um encontro potente entre gera\u00e7\u00f5es durante o Festival da Juventude 2026. A mesa &#8220;Conex\u00e3o Gera\u00e7\u00f5es \u2013 A Pol\u00edtica \u00e9 Para Mim? Desafios e Oportunidades para a Juventude&#8221;, realizada nesta sexta-feira (27), no Audit\u00f3rio Mar\u00e7al de Souza Tup\u00e3-Y, na UFMS, reuniu estudantes de escolas p\u00fablicas, universit\u00e1rios e lideran\u00e7as pol\u00edticas para um debate direto: afinal, qual \u00e9 o lugar da juventude na pol\u00edtica?<\/p>\n<p>Com trajet\u00f3rias distintas, os deputados federais Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es sobre participa\u00e7\u00e3o, cidadania e futuro.<\/p>\n<p>Entre os participantes, quem chamou aten\u00e7\u00e3o foi o estudante de escola p\u00fablica Alessandro Rog\u00e9rio, de apenas 11 anos de idade. Para ele, o espa\u00e7o foi mais do que uma atividade do festival, foi oportunidade de pertencimento:<\/p>\n<p>&#8220;Eu tirei muitos ensinamentos e achei bem legal, porque \u00e9 uma oportunidade de a gente estar perto de lideran\u00e7as que criam leis. A quest\u00e3o da mobilidade \u00e9 muito importante e foi falada aqui. Nos debates, geralmente focam nos adultos e esquecem a galera mais nova, e aqui foi diferente. A gente tamb\u00e9m pode contribuir&#8221;.<\/p>\n<p>Para Camila Jara, o distanciamento entre pol\u00edtica e sociedade ainda \u00e9 um desafio que precisa ser enfrentado desde cedo. &#8220;A pol\u00edtica precisa estar inserida na sociedade. A gente n\u00e3o aprende na sala de aula para onde v\u00e3o os nossos impostos ou por que precisamos debater as quest\u00f5es b\u00e1sicas do nosso dia a dia. Quando temos a oportunidade de falar com os jovens e mostrar a proximidade deles enquanto cidad\u00e3os, estamos exercendo nosso papel. Esse encontro foi fundamental&#8221;.<\/p>\n<p>Com mais de tr\u00eas d\u00e9cadas de vida p\u00fablica, Vander Loubet ressaltou o impacto do encontro como um espa\u00e7o de renova\u00e7\u00e3o e troca. &#8220;Isso aqui rejuvenesce a gente. \u00c9 uma conex\u00e3o impressionante, principalmente poder dialogar com essa garotada. A pol\u00edtica est\u00e1 em tudo: n\u00e3o s\u00f3 a partid\u00e1ria, mas no gr\u00eamio estudantil, no bairro, na comunidade. \u00c9 da\u00ed que surgem novas lideran\u00e7as, que no futuro v\u00e3o nos substituir&#8221;.<\/p>\n<p><img decoding=\"async\" class=\"size-large wp-image-20686 alignnone\" src=\"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-vander-camila-frebraro-700x467.jpg\" alt=\"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv\" width=\"696\" height=\"464\" srcset=\"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-vander-camila-frebraro-700x467.jpg 700w, https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-vander-camila-frebraro-350x233.jpg 350w, https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-vander-camila-frebraro-768x512.jpg 768w, https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-vander-camila-frebraro-630x420.jpg 630w, https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-vander-camila-frebraro-696x464.jpg 696w, https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-vander-camila-frebraro.jpg 960w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p><strong>Vozes ampliadas<\/strong><\/p>\n<p>Mais do que um debate, a mesa mostrou que o Festival da Juventude cumpre um papel essencial: n\u00e3o dar voz, mas ampliar as vozes que j\u00e1 existem. A diversidade de participantes e a troca entre gera\u00e7\u00f5es refor\u00e7am a pot\u00eancia do evento como espa\u00e7o de forma\u00e7\u00e3o, escuta e protagonismo juvenil.<\/p>\n<p>Para a coordenadora geral do FestJuv, Andr\u00e9a Freire, a segunda edi\u00e7\u00e3o do festival refor\u00e7a o compromisso de construir um espa\u00e7o onde os jovens n\u00e3o estejam apenas na plateia, mas sejam protagonistas.<\/p>\n<p>&#8220;A gente acredita na participa\u00e7\u00e3o ativa, no di\u00e1logo e na troca como caminhos para fortalecer pol\u00edticas p\u00fablicas e tamb\u00e9m a pr\u00f3pria viv\u00eancia da juventude. Realizar o Festival dentro de um campus universit\u00e1rio tem um significado muito importante: aproximar esses jovens de um espa\u00e7o de forma\u00e7\u00e3o, de futuro e de possibilidades&#8221;.<\/p>\n<p>O Festival segue com programa\u00e7\u00e3o at\u00e9 s\u00e1bado (26). <a href=\"https:\/\/festjuv.com.br\/2026\/programacao\/\" target=\"_blank\" rel=\"noopener\">Acesse o site oficial <\/a>ou as<a href=\"https:\/\/www.instagram.com\/festivaldajuventudems\" target=\"_blank\" rel=\"noopener\"> redes sociais<\/a>\u00a0e fique por dentro das atividades.<\/p>\n<p>O Festival da Juventude \u00e9 uma realiza\u00e7\u00e3o do Instituto Curumins, em parceria com a UFMS e o Minist\u00e9rio da Cultura, por meio de emenda parlamentar do deputado federal Vander Loubet, al\u00e9m do apoio da Lei Federal de Incentivo \u00e0 Cultura (Lei Rouanet), do Fundo Nacional de Cultura e do Governo Federal. Conta ainda com o apoio da Secretaria de Estado da Cidadania (SEC), Subsecretaria da Juventude (SubsJuventude), Secretaria de Estado de Turismo, Esporte e Cultura (Setesc), Secretaria de Estado de Educa\u00e7\u00e3o (SED), Funda\u00e7\u00e3o de Cultura de MS, Rede Educativa MS, Governo do Estado, senadora Soraya Thronicke, deputada federal Camila Jara e \u00c1guas Guariroba.<\/p>\n<pre><em>Texto: Arruda Comunica\u00e7\u00e3o<\/em>\r\n<em>Fotos: Alex Nantes<\/em><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Com trajet\u00f3rias distintas, Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es.<\/p>\n","protected":false},"author":2,"featured_media":20683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2099,10],"tags":[342,562,2127,1109],"class_list":{"0":"post-20682","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ms-noticias","8":"category-noticias","9":"tag-campo-grande","10":"tag-cultura","11":"tag-emenda-parlamentar","12":"tag-juventude"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv<\/title>\n<meta name=\"description\" content=\"Com trajet\u00f3rias distintas, Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv\" \/>\n<meta property=\"og:description\" content=\"Com trajet\u00f3rias distintas, Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/\" \/>\n<meta property=\"og:site_name\" content=\"Deputado Federal Vander Loubet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/deputadovander\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T20:20:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-27T21:47:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-conversas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9der\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vanderloubet\" \/>\n<meta name=\"twitter:site\" content=\"@vanderloubet\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/\"},\"author\":{\"name\":\"\u00c9der\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#\\\/schema\\\/person\\\/15b51bd564532a8a68d9dec1b8eb890e\"},\"headline\":\"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv\",\"datePublished\":\"2026-03-27T20:20:13+00:00\",\"dateModified\":\"2026-03-27T21:47:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/\"},\"wordCount\":649,\"publisher\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/foto-2026-03-27-festjuv-mesa-conversas.jpg\",\"keywords\":[\"campo grande\",\"cultura\",\"emenda parlamentar\",\"juventude\"],\"articleSection\":[\"Mato Grosso do Sul\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/\",\"url\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/\",\"name\":\"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/foto-2026-03-27-festjuv-mesa-conversas.jpg\",\"datePublished\":\"2026-03-27T20:20:13+00:00\",\"dateModified\":\"2026-03-27T21:47:01+00:00\",\"description\":\"Com trajet\u00f3rias distintas, Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/foto-2026-03-27-festjuv-mesa-conversas.jpg\",\"contentUrl\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/foto-2026-03-27-festjuv-mesa-conversas.jpg\",\"width\":960,\"height\":640,\"caption\":\"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#website\",\"url\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/\",\"name\":\"Deputado Federal Vander Loubet\",\"description\":\"O Federal de MS\",\"publisher\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#organization\"},\"alternateName\":\"Deputado Vander\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#organization\",\"name\":\"Deputado Federal Vander Loubet\",\"alternateName\":\"Deputado Vander\",\"url\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/foto-2023-06-19-mandato-deputado-vander.jpg\",\"contentUrl\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/foto-2023-06-19-mandato-deputado-vander.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Deputado Federal Vander Loubet\"},\"image\":{\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/deputadovander\",\"https:\\\/\\\/x.com\\\/vanderloubet\",\"https:\\\/\\\/instagram.com\\\/vanderloubet\",\"https:\\\/\\\/youtube.com\\\/vanderloubet\",\"https:\\\/\\\/tiktok.com\\\/@vanderloubetms\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/#\\\/schema\\\/person\\\/15b51bd564532a8a68d9dec1b8eb890e\",\"name\":\"\u00c9der\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/litespeed\\\/avatar\\\/88ca4090d9d5ab1c9495f6ca03b68efa.jpg?ver=1778268715\",\"url\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/litespeed\\\/avatar\\\/88ca4090d9d5ab1c9495f6ca03b68efa.jpg?ver=1778268715\",\"contentUrl\":\"https:\\\/\\\/vanderloubet.com.br\\\/deputado\\\/wp-content\\\/litespeed\\\/avatar\\\/88ca4090d9d5ab1c9495f6ca03b68efa.jpg?ver=1778268715\",\"caption\":\"\u00c9der\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv","description":"Com trajet\u00f3rias distintas, Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/","og_locale":"pt_BR","og_type":"article","og_title":"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv","og_description":"Com trajet\u00f3rias distintas, Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es.","og_url":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/","og_site_name":"Deputado Federal Vander Loubet","article_publisher":"https:\/\/facebook.com\/deputadovander","article_published_time":"2026-03-27T20:20:13+00:00","article_modified_time":"2026-03-27T21:47:01+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-conversas.jpg","type":"image\/jpeg"}],"author":"\u00c9der","twitter_card":"summary_large_image","twitter_creator":"@vanderloubet","twitter_site":"@vanderloubet","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/#article","isPartOf":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/"},"author":{"name":"\u00c9der","@id":"https:\/\/vanderloubet.com.br\/deputado\/#\/schema\/person\/15b51bd564532a8a68d9dec1b8eb890e"},"headline":"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv","datePublished":"2026-03-27T20:20:13+00:00","dateModified":"2026-03-27T21:47:01+00:00","mainEntityOfPage":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/"},"wordCount":649,"publisher":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/#organization"},"image":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/#primaryimage"},"thumbnailUrl":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-conversas.jpg","keywords":["campo grande","cultura","emenda parlamentar","juventude"],"articleSection":["Mato Grosso do Sul","Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/","url":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/","name":"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv","isPartOf":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/#primaryimage"},"image":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/#primaryimage"},"thumbnailUrl":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-conversas.jpg","datePublished":"2026-03-27T20:20:13+00:00","dateModified":"2026-03-27T21:47:01+00:00","description":"Com trajet\u00f3rias distintas, Vander Loubet e Camila Jara conduziram a conversa, compartilhando experi\u00eancias e provocando reflex\u00f5es.","breadcrumb":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/#primaryimage","url":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-conversas.jpg","contentUrl":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-conversas.jpg","width":960,"height":640,"caption":"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv"},{"@type":"BreadcrumbList","@id":"https:\/\/vanderloubet.com.br\/deputado\/politica-como-ferramenta-de-transformacao-marca-mesa-de-conversas-do-festjuv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vanderloubet.com.br\/deputado\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica como ferramenta de transforma\u00e7\u00e3o marca mesa de conversas do FestJuv"}]},{"@type":"WebSite","@id":"https:\/\/vanderloubet.com.br\/deputado\/#website","url":"https:\/\/vanderloubet.com.br\/deputado\/","name":"Deputado Federal Vander Loubet","description":"O Federal de MS","publisher":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/#organization"},"alternateName":"Deputado Vander","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vanderloubet.com.br\/deputado\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/vanderloubet.com.br\/deputado\/#organization","name":"Deputado Federal Vander Loubet","alternateName":"Deputado Vander","url":"https:\/\/vanderloubet.com.br\/deputado\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vanderloubet.com.br\/deputado\/#\/schema\/logo\/image\/","url":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2023\/06\/foto-2023-06-19-mandato-deputado-vander.jpg","contentUrl":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2023\/06\/foto-2023-06-19-mandato-deputado-vander.jpg","width":1080,"height":1080,"caption":"Deputado Federal Vander Loubet"},"image":{"@id":"https:\/\/vanderloubet.com.br\/deputado\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/deputadovander","https:\/\/x.com\/vanderloubet","https:\/\/instagram.com\/vanderloubet","https:\/\/youtube.com\/vanderloubet","https:\/\/tiktok.com\/@vanderloubetms"]},{"@type":"Person","@id":"https:\/\/vanderloubet.com.br\/deputado\/#\/schema\/person\/15b51bd564532a8a68d9dec1b8eb890e","name":"\u00c9der","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/litespeed\/avatar\/88ca4090d9d5ab1c9495f6ca03b68efa.jpg?ver=1778268715","url":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/litespeed\/avatar\/88ca4090d9d5ab1c9495f6ca03b68efa.jpg?ver=1778268715","contentUrl":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/litespeed\/avatar\/88ca4090d9d5ab1c9495f6ca03b68efa.jpg?ver=1778268715","caption":"\u00c9der"}}]}},"jetpack_featured_media_url":"https:\/\/vanderloubet.com.br\/deputado\/wp-content\/uploads\/2026\/03\/foto-2026-03-27-festjuv-mesa-conversas.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/posts\/20682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/comments?post=20682"}],"version-history":[{"count":5,"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/posts\/20682\/revisions"}],"predecessor-version":[{"id":20689,"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/posts\/20682\/revisions\/20689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/media\/20683"}],"wp:attachment":[{"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/media?parent=20682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/categories?post=20682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vanderloubet.com.br\/deputado\/wp-json\/wp\/v2\/tags?post=20682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}